{"id":174,"date":"2022-10-17T14:09:00","date_gmt":"2022-10-17T17:09:00","guid":{"rendered":"http:\/\/wsoftnet.com.br\/wsblog\/?p=174"},"modified":"2022-11-16T14:26:28","modified_gmt":"2022-11-16T17:26:28","slug":"sebrae-se-une-a-caixa-para-formalizar-30-milhoes-de-mulheres-empreendedoras-no-pais","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/sebrae-se-une-a-caixa-para-formalizar-30-milhoes-de-mulheres-empreendedoras-no-pais\/","title":{"rendered":"Sebrae se une \u00e0 Caixa para formalizar 30 milh\u00f5es de mulheres empreendedoras no pa\u00eds"},"content":{"rendered":"\n<p><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"343\" class=\"wp-image-175\" style=\"width: 567px;\" src=\"http:\/\/wsoftnet.com.br\/wsblog\/wp-content\/uploads\/2022\/11\/Caixa_pra_elas.png\" alt=\"\" srcset=\"https:\/\/wsoftnet.com.br\/wsblog\/wp-content\/uploads\/2022\/11\/Caixa_pra_elas.png 567w, https:\/\/wsoftnet.com.br\/wsblog\/wp-content\/uploads\/2022\/11\/Caixa_pra_elas-300x181.png 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/p>\n\n\n\n<p>At\u00e9 19 de novembro, Dia Mundial do Empreendedorismo Feminino, est\u00e3o previstas diversas a\u00e7\u00f5es de atendimento do Sebrae e da Caixa com foco no atendimento \u00e0s mulheres por todo o pa\u00eds, em mutir\u00f5es programados. O primeiro deles ser\u00e1 nesta ter\u00e7a-feira (18), no Mega Polo de Moda, em S\u00e3o Paulo. O programa vai disponibilizar R$ 1 bilh\u00e3o em cr\u00e9dito para as mulheres empreendedoras que buscarem atendimento.<\/p>\n\n\n\n<p>As linhas de cr\u00e9dito oferecidas para as mulheres tamb\u00e9m ser\u00e3o customizadas para melhor atender \u00e0s necessidades de acordo com cada perfil, seja empreendedora informal, rec\u00e9m-formalizada ou j\u00e1 formalizada h\u00e1 mais de 12 meses. De imediato, o cr\u00e9dito oferecido \u00e9 de at\u00e9 R$ 1 mil, mas, ap\u00f3s tr\u00eas meses, ser\u00e1 poss\u00edvel realizar a antecipa\u00e7\u00e3o de receb\u00edveis ou da maquininha de acordo com o faturamento.<\/p>\n\n\n\n<p>A partir de sete meses de neg\u00f3cio, a empreendedora pode contar com o Cr\u00e9dito MEI, por meio do microcr\u00e9dito do Fundo de Aval \u00e0s Micro e Pequenas Empresas do Sebrae (FAMPE). Aos 12 meses, o cr\u00e9dito oferecido pode ser de at\u00e9 R$ 300 mil, por meio do Programa Nacional de Apoio \u00e0s Microempresas e Empresas de Pequeno Porte (Pronampe), FAMPE e outras linhas de cr\u00e9dito dispon\u00edveis.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Sebrae<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 19 de novembro, Dia Mundial do Empreendedorismo Feminino, est\u00e3o previstas diversas a\u00e7\u00f5es de atendimento do Sebrae e da Caixa [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-174","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"predecessor-version":[{"id":176,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/174\/revisions\/176"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}