{"id":232,"date":"2023-04-24T10:51:02","date_gmt":"2023-04-24T13:51:02","guid":{"rendered":"http:\/\/wsoftnet.com.br\/wsblog\/?p=232"},"modified":"2023-04-24T10:51:02","modified_gmt":"2023-04-24T13:51:02","slug":"micro-e-pequenas-empresas-criaram-85-das-vagas-de-trabalho-geradas-em-fevereiro-2023","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/micro-e-pequenas-empresas-criaram-85-das-vagas-de-trabalho-geradas-em-fevereiro-2023\/","title":{"rendered":"Micro e pequenas empresas criaram 85% das vagas de trabalho geradas em fevereiro\/2023."},"content":{"rendered":"\n<p>Levantamento do Sebrae, com base em dados do Caged, aponta que segmento foi respons\u00e1vel por 206 mil contrata\u00e7\u00f5es.<\/p>\n\n\n\n<p>As micro e pequenas empresas (MPE) continuam puxando a gera\u00e7\u00e3o de empregos formais no Brasil. Em fevereiro, dos 241.785 novos postos de trabalho criados, 85,5% foram nas MPE. Isso representa 206.697 vagas abertas, em n\u00fameros absolutos. As m\u00e9dias e grandes empresas apresentaram saldo negativo pelo segundo m\u00eas consecutivo, com mais desligamentos do que admiss\u00f5es.<\/p>\n\n\n\n<p>Os dados s\u00e3o de levantamento feito pelo Sebrae com base nos n\u00fameros do Cadastro Geral de Empregados e Desempregados (Caged) referentes a fevereiro de 2023. Se comparado com o mesmo m\u00eas do ano passado, houve uma queda de 6,4% no saldo de empregos gerados pelas micro e pequenas empresas, que criaram 220.775 postos em fevereiro de 2022, ante 206.697 no mesmo per\u00edodo de 2023.<\/p>\n\n\n\n<p>Apesar da queda na compara\u00e7\u00e3o com o mesmo m\u00eas do ano passado, na m\u00e9dia, as MPE permanecem como uma pot\u00eancia de cria\u00e7\u00e3o de vagas de trabalho. No acumulado de 2023, dos 326.356 novos empregos gerados, 83% foram nas micro e pequenas empresas.<\/p>\n\n\n\n<p>\u201cOs dados atestam a import\u00e2ncia dos pequenos neg\u00f3cios para a economia nacional, gerando renda e contribuindo para assegurar a cidadania de milhares de pessoas e suas fam\u00edlias. Falar de desenvolvimento econ\u00f4mico e social \u00e9 falar da micro e pequena empresa\u201d, afirma D\u00e9cio Lima, presidente do Sebrae.<\/p>\n\n\n\n<p><strong>Por segmento<\/strong><\/p>\n\n\n\n<p>O setor de servi\u00e7os das micro e pequenas empresas foi o que mais contratou, com a abertura de 135.238 empregos em fevereiro deste ano. Em seguida, vem a Ind\u00fastria de Transforma\u00e7\u00e3o, com 37.429 vagas; e a Constru\u00e7\u00e3o, respondendo por 22.600 dos novos empregos gerados. O Com\u00e9rcio, por sua vez, teve saldo negativo (-1.344 novos postos de trabalho).<\/p>\n\n\n\n<p><strong>Dados por ano<\/strong><\/p>\n\n\n\n<p>Em 2022, a cada 10 postos de trabalho gerados no Brasil, aproximadamente 8 foram criados pelas micro e pequenas empresas. O acumulado do ano ultrapassou 2 milh\u00f5es de novas vagas, das quais quase 1,6 milh\u00e3o foram nos pequenos neg\u00f3cios: cerca de 78,4% do total. Em 2021, a participa\u00e7\u00e3o das MPE no saldo total foi de 77%. J\u00e1 nos dois primeiros meses de 2023, as micro e pequenas empresas est\u00e3o respondendo por 83% do total.<\/p>\n\n\n\n<p>Fonte: SEBRAE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Levantamento do Sebrae, com base em dados do Caged, aponta que segmento foi respons\u00e1vel por 206 mil contrata\u00e7\u00f5es. As micro [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-232","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"predecessor-version":[{"id":233,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/232\/revisions\/233"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}