{"id":262,"date":"2023-05-11T08:29:03","date_gmt":"2023-05-11T11:29:03","guid":{"rendered":"http:\/\/wsoftnet.com.br\/wsblog\/?p=262"},"modified":"2023-05-11T08:29:03","modified_gmt":"2023-05-11T11:29:03","slug":"aprovado-fim-do-icms-para-transito-interestadual-de-produto-da-mesma-empresa","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/aprovado-fim-do-icms-para-transito-interestadual-de-produto-da-mesma-empresa\/","title":{"rendered":"Aprovado fim do ICMS para tr\u00e2nsito interestadual de produto da mesma empresa."},"content":{"rendered":"\n<p>O Plen\u00e1rio do Senado aprovou, com 62 votos a favor e nenhum contr\u00e1rio, o projeto de lei que acaba com a cobran\u00e7a de ICMS sobre mercadorias que saem do dep\u00f3sito em um estado e v\u00e3o para uma loja da mesma rede varejista em outro estado. O PLS 332\/2018, de autoria do ent\u00e3o senador Fernando Bezerra Coelho, foi relatado pelo senador Iraj\u00e1 (PSD-TO) e segue agora para vota\u00e7\u00e3o na C\u00e2mara dos Deputados.<\/p>\n\n\n\n<p>\u2014 \u00c9 uma mat\u00e9ria extremamente importante ao pa\u00eds, aos estados brasileiros, porque ela vai uniformizar o entendimento do Supremo Tribunal Federal, na ADC 49, onde o pr\u00f3prio Supremo veda a cobran\u00e7a de ICMS entre os mesmos estabelecimentos que est\u00e3o em estados diferentes. (\u2026) \u00c9 uma mat\u00e9ria que corrige uma injusti\u00e7a, uma distor\u00e7\u00e3o tribut\u00e1ria, a conhecida bitributa\u00e7\u00e3o \u2014 explicou o senador Iraj\u00e1.<\/p>\n\n\n\n<p>Atualmente a Lei Kandir (Lei Complementar 87, de 1996) determina a incid\u00eancia de ICMS no momento da sa\u00edda de mercadoria do estabelecimento, ainda que para outro estabelecimento do mesmo propriet\u00e1rio. O projeto retira a possibilidade de essa cobran\u00e7a ser feita quando da transfer\u00eancia da mercadoria para estabelecimento do mesmo titular.<\/p>\n\n\n\n<p>Al\u00e9m disso, o texto deixa claro que n\u00e3o h\u00e1 \u201cfato gerador do imposto\u201d apenas com a movimenta\u00e7\u00e3o de produtos entre estabelecimentos do mesmo dono. Nesse caso, ser\u00e1 mantido o cr\u00e9dito tribut\u00e1rio em favor do titular<\/p>\n\n\n\n<p>O senador Iraj\u00e1 inseriu no texto a autoriza\u00e7\u00e3o para que seja feita a incid\u00eancia e o destaque do imposto (declara\u00e7\u00e3o do valor do ICMS na nota fiscal) na sa\u00edda da mercadoria de um estabelecimento para outro estabelecimento do mesmo titular. Nessa hip\u00f3tese, o imposto destacado na sa\u00edda pode ser considerado cr\u00e9dito tribut\u00e1rio pelo estabelecimento destinat\u00e1rio.<\/p>\n\n\n\n<p>\u2014 Com isso, busca-se evitar que estabelecimentos que enviem mercadorias para filiais em outros estados sejam prejudicados pela perda de eventuais incentivos fiscais em vigor \u2014 argumentou o relator.<\/p>\n\n\n\n<p>De acordo com ele, o projeto busca proibir a cobran\u00e7a de imposto em uma simples transfer\u00eancia de estoque, seguindo decis\u00e3o do Supremo Tribunal Federal (STF).<\/p>\n\n\n\n<p>Tamb\u00e9m participaram do debate os senadores Jayme Campos (Uni\u00e3o-MT), Margareth Buzetti (PSD-MT), Jayme Bagattoli (PL-RO), La\u00e9rcio Oliveira (PP-SE), Eduardo Braga (MDB-AM), Otto Alencar (PSD-BA), Efraim Filho (Uni\u00e3o-PB), Jaques Wagner (PT-BA) e outros.<\/p>\n\n\n\n<p>\u2014 Essa mat\u00e9ria, senador Iraj\u00e1, est\u00e1 na pauta priorit\u00e1ria da Frente Parlamentar do Com\u00e9rcio, Servi\u00e7os e Empreendedorismo, a qual tenho a honra de presidir. Ela \u00e9 important\u00edssima para que a gente simplifique o sistema, desburocratize e valorize quem produz. (\u2026) \u00c9 importante que toda modifica\u00e7\u00e3o venha no sentido de facilitar a vida de quem produz \u2014 disse Efraim Filho.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Senado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Plen\u00e1rio do Senado aprovou, com 62 votos a favor e nenhum contr\u00e1rio, o projeto de lei que acaba com [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-262","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/262\/revisions"}],"predecessor-version":[{"id":263,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/262\/revisions\/263"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}