{"id":269,"date":"2023-08-24T08:44:58","date_gmt":"2023-08-24T11:44:58","guid":{"rendered":"http:\/\/wsoftnet.com.br\/wsblog\/?p=269"},"modified":"2023-08-24T08:44:58","modified_gmt":"2023-08-24T11:44:58","slug":"tribunal-de-contas-da-uniao-e-secretaria-extraordinaria-da-reforma-tributaria-analisam-estudo-relacionado-a-tributacao-sobre-o-consumo","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/tribunal-de-contas-da-uniao-e-secretaria-extraordinaria-da-reforma-tributaria-analisam-estudo-relacionado-a-tributacao-sobre-o-consumo\/","title":{"rendered":"Tribunal de Contas da Uni\u00e3o e Secretaria Extraordin\u00e1ria da Reforma Tribut\u00e1ria analisam estudo relacionado \u00e0 tributa\u00e7\u00e3o sobre o consumo."},"content":{"rendered":"\n<p>Reuni\u00e3o com equipes do Minist\u00e9rio da Fazenda e do Senado Federal faz parte da s\u00e9rie de encontros que v\u00eam sendo realizados pelo Grupo de Trabalho criado pelo TCU para auxiliar em quest\u00f5es relacionadas \u00e0 reforma tribut\u00e1ria.<\/p>\n\n\n\n<p>Nesta ter\u00e7a-feira (8\/8), o Grupo de Trabalho (GT) criado pelo Tribunal de Contas da Uni\u00e3o (TCU) para auxiliar em quest\u00f5es relacionadas \u00e0 reforma tribut\u00e1ria se reuniu com equipes do Minist\u00e9rio da Fazenda e do Senado Federal. O encontro tratou do levantamento de dados e informa\u00e7\u00f5es relacionados \u00e0 tributa\u00e7\u00e3o sobre o consumo, objeto da reforma tribut\u00e1ria em tramita\u00e7\u00e3o no Senado.<\/p>\n\n\n\n<p>A agenda faz parte de uma s\u00e9rie de reuni\u00f5es que o GT tem realizado com atores estrat\u00e9gicos para o assunto. Representantes da Secretaria Extraordin\u00e1ria da Reforma Tribut\u00e1ria, da Receita Federal, do gabinete do senador Eduardo Braga \u2013 relator da reforma tribut\u00e1ria no Senado \u2013 e da consultoria daquela Casa participaram.<\/p>\n\n\n\n<p>O secret\u00e1rio extraordin\u00e1rio da Reforma Tribut\u00e1ria, Bernard Appy, detalhou o estudo realizado pelos t\u00e9cnicos do Minist\u00e9rio da Fazenda e que foi entregue pelo titular da pasta, Fernando Haddad, ao relator da Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) 45\/2019, senador Eduardo Braga.<\/p>\n\n\n\n<p>Tiago Dutra, secret\u00e1rio de Controle Externo de Contas P\u00fablicas do TCU, ressaltou que o principal papel da Corte de Contas \u00e9 confirmar a confiabilidade desses dados. A cria\u00e7\u00e3o do GT leva em considera\u00e7\u00e3o as atribui\u00e7\u00f5es do Tribunal em auxiliar o Congresso Nacional no controle externo das contas p\u00fablicas, incluindo receitas e cr\u00e9ditos tribut\u00e1rios.<\/p>\n\n\n\n<p><strong>Estudo revela impactos da reforma tribut\u00e1ria.<\/strong><\/p>\n\n\n\n<p>Durante a reuni\u00e3o, Appy explicou que os cen\u00e1rios simulados no levantamento do Minist\u00e9rio da Fazenda levaram em considera\u00e7\u00e3o o hiato de conformidade, ou seja, a diferen\u00e7a entre o potencial de arrecada\u00e7\u00e3o de tributos sobre o consumo e a arrecada\u00e7\u00e3o efetivamente obtida.<\/p>\n\n\n\n<p>Nos c\u00e1lculos da pasta, a al\u00edquota padr\u00e3o do Imposto e da Contribui\u00e7\u00e3o sobre Bens e Servi\u00e7os (IBS e CBS), que substituir\u00e3o cinco tributos incidentes sobre o consumo, ficar\u00e1 entre 25,45% e 27%, levando-se em considera\u00e7\u00e3o o texto aprovado na C\u00e2mara dos Deputados. Conforme o estudo, a carga tribut\u00e1ria atual sobre o consumo, considerando al\u00edquotas m\u00e9dias de PIS e ICMS, est\u00e1 em torno de 34,4%.<\/p>\n\n\n\n<p>O estudo tamb\u00e9m simulou os impactos de cada tratamento favorecido ou diferenciado na composi\u00e7\u00e3o da al\u00edquota final da soma do IBS com a CBS, tais como hotelaria, servi\u00e7os de transporte coletivo, produ\u00e7\u00f5es jornal\u00edsticas, bares, restaurantes, entre outros. Segundo a nota t\u00e9cnica, cada exce\u00e7\u00e3o representaria um incremento na al\u00edquota final.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao Conselho Federativo do IBS, Appy destacou que o \u00f3rg\u00e3o \u00e9 necess\u00e1rio para gerir a arrecada\u00e7\u00e3o, tratar do contencioso administrativo e uniformizar as obriga\u00e7\u00f5es acess\u00f3rias e a interpreta\u00e7\u00e3o da legisla\u00e7\u00e3o em \u00e2mbito nacional. O secret\u00e1rio ressaltou a import\u00e2ncia do conselho para diminuir a burocracia tribut\u00e1ria, lembrando que a compet\u00eancia ser\u00e1 compartilhada entre os entes subnacionais.<\/p>\n\n\n\n<p>Fonte: FENACON<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reuni\u00e3o com equipes do Minist\u00e9rio da Fazenda e do Senado Federal faz parte da s\u00e9rie de encontros que v\u00eam sendo [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-269","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=269"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/269\/revisions"}],"predecessor-version":[{"id":270,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/269\/revisions\/270"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}