{"id":301,"date":"2023-09-27T09:00:37","date_gmt":"2023-09-27T12:00:37","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=301"},"modified":"2023-09-27T09:00:38","modified_gmt":"2023-09-27T12:00:38","slug":"sao-paulo-se-prepara-para-calor-que-pode-atingir-marcas-recordes","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/sao-paulo-se-prepara-para-calor-que-pode-atingir-marcas-recordes\/","title":{"rendered":"S\u00e3o Paulo se prepara para calor que pode atingir marcas recordes."},"content":{"rendered":"\n<p>Temperatura no domingo (24.09.23) e no come\u00e7o da semana que vem ser\u00e1 extrema. Calor ter\u00e1 uma escalada nos pr\u00f3ximos dias.<\/p>\n\n\n\n<p>O calor \u00e9 ainda moderado na cidade de S\u00e3o Paulo, mas vai aumentar muito durante os pr\u00f3ximos dias e se tornar\u00e1 intenso a extremo, com possibilidade de atingir marcas at\u00e9 hist\u00f3ricas e talvez sem precedentes na capital paulista. Diante das condi\u00e7\u00f5es de calor excepcional que se avizinham, as autoridades come\u00e7am a adotar algumas a\u00e7\u00f5es.<\/p>\n\n\n\n<p>A temperatura m\u00e1xima oficial nesta quarta-feira na esta\u00e7\u00e3o do Instituto Nacional de Meteorologia na cidade de S\u00e3o Paulo, no Mirante de Santana, chegou a 31,4\u00baC, o que \u00e9 um n\u00edvel de calor absolutamente normal. No interior, o \u00f3rg\u00e3o registrou m\u00e1xima de 38,2\u00baC em Valpara\u00edso. Na rede do Ciiaro, Ara\u00e7atuba anotou 39,4\u00baC.<\/p>\n\n\n\n<p>O calor, entretanto, deve aumentar muito nos pr\u00f3ximos dias na capital, no litoral e no interior. A escala da temperatura come\u00e7ar\u00e1 nesta quinta-feira e vai ganhar for\u00e7a de sexta-feira em diante com m\u00e1ximas muito distantes do que normalmente poderia se esperar nesta \u00e9poca do ano.<\/p>\n\n\n\n<p>Na cidade de S\u00e3o Paulo, as m\u00e1ximas nesta quinta devem ficar entre 31\u00baC e 33\u00baC. Na sexta, o calor aumenta muito e a tarde deve ser t\u00f3rrida com os term\u00f4metros apontando entre 34\u00baC e 36\u00baC, n\u00e3o se afastando at\u00e9 37\u00baC em alguns pontos. No s\u00e1bado, o calor cede um pouco e as m\u00e1ximas devem ficar entre 32\u00baC e 34\u00baC.<\/p>\n\n\n\n<p>No domingo, a temperatura atinge marcas extremas com possibilidade de m\u00e1ximas de 36\u00baC a 38\u00baC e at\u00e9 entre 38\u00baC e 40\u00baC em alguns locais. Na segunda, conforme os mais recentes dados, o calor recuaria para 35\u00baC a 36\u00baC. Na ter\u00e7a, contudo, poderia atigir picos extremos de 38\u00baC a 40\u00baC com chance de marcas isoladas superiores a 40\u00baC pelo efeito da ilha de calor urbano, o que \u00e9 espantoso pela climatologia da cidade de S\u00e3o Paulo.<\/p>\n\n\n\n<p>No interior, o calor ganha tamb\u00e9m muita for\u00e7a nos pr\u00f3ximos dias. Na sexta, no fim de semana e no come\u00e7o da semana que vem haver\u00e1 m\u00e1ximas em muitas cidades ou mesmo generalizadas acima de 40\u00baC no interior de S\u00e3o Paulo com marcas de 41\u00baC a 44\u00baC em diversas cidades.<\/p>\n\n\n\n<p><strong>RECORDES PODEM CAIR<\/strong><\/p>\n\n\n\n<p>Considerando os dados que insistem em marcas extremas, \u00e9 poss\u00edvel que caiam v\u00e1rios recordes de temperatura no estado de S\u00e3o Paulo, na capital e no interior. A maioria de maior m\u00e1xima j\u00e1 anotada em setembro, mas em algumas cidades at\u00e9 absolutos para toda a s\u00e9rie hist\u00f3rica (todos os meses do ano).<\/p>\n\n\n\n<p>O dia mais quente j\u00e1 registrado na cidade de S\u00e3o Paulo em setembro desde o come\u00e7o dos dados em 1943 na esta\u00e7\u00e3o do Mirante de Santana foi de 37,1\u00baC, em 30 de setembro de 2020. Trata-se da segunda maior m\u00e1xima da s\u00e9rie hist\u00f3rica, s\u00f3 atr\u00e1s dos 37,8 \u00baC de 17 de outubro de 2014.<\/p>\n\n\n\n<p>Outros dias de calor muito intenso na s\u00e9rie da esta\u00e7\u00e3o do Mirante de Santana, esta\u00e7\u00e3o na zona Norte da cidade do Instituto Nacional de Meteorologia, incluem os registros de 37,0\u00baC em 20 de janeiro de 1999, 36,7\u00baC em 19 de janeiro de 1999 e tamb\u00e9m 36,7\u00baC em 21 de janeiro de 1999.<\/p>\n\n\n\n<p>Com base nos registros absolutos de todo estado de S\u00e3o Paulo, a partir dos dados de esta\u00e7\u00f5es meteorol\u00f3gicas convencionais e autom\u00e1ticas do Instituto Nacional de Meteorologia, as maiores m\u00e1ximas j\u00e1 observadas no estado de S\u00e3o Paulo s\u00e3o: 43,5\u00b0C em Lins em 07\/10\/2020; 43,0\u00b0C em Iguape em 03\/02\/1933; 42,9\u00b0C em Barretos em 07\/10\/2020; 42,8\u00b0C em Registro em 02\/10\/2020; 42,6\u00b0C em Ibitinga em 07\/10\/2020; 42,4\u00b0C em Dracena em 06\/10\/2020; 42,2\u00b0C em Catanduva em 05\/10\/2020; 42,1\u00b0C em Iguape em 16\/01\/1956, e Catanduva e Votuporanga em 03\/10\/2020; e 42,0\u00b0C em Jales em 07\/10\/2020.<\/p>\n\n\n\n<p><strong>CIDADE DE S\u00c3O PAULO SE PREPARA PARA O CALOR EXTREMO<\/strong><\/p>\n\n\n\n<p>Mesmo distante do ideal e das melhores pr\u00e1ticas mundiais em ondas de calor extremo, diante do calor que se avizinha a cidade de S\u00e3o Paulo anunciou um conjunto de a\u00e7\u00f5es ante a perspectiva de marcas incomuns de temperatura alta nos pr\u00f3ximos dias.<\/p>\n\n\n\n<p>Focada em pessoas em situa\u00e7\u00e3o de vulnerabilidade, a Prefeitura de S\u00e3o Paulo criou a Opera\u00e7\u00e3o Altas Temperaturas, que come\u00e7ou a vigorar nesta quarta-feira. Similar \u00e0 Opera\u00e7\u00e3o Baixas Temperaturas, a de altas temperaturas ser\u00e1 mobilizada sempre que os term\u00f4metros atingirem 32\u00baC, ou sensa\u00e7\u00e3o equivalente. A a\u00e7\u00e3o \u00e9 feita em parceria com o governo do Estado, por meio da Sabesp.<\/p>\n\n\n\n<p>As principais a\u00e7\u00f5es ter\u00e3o foco no refor\u00e7o no convencimento das pessoas para procurarem a rede de acolhimento, onde poder\u00e3o se abrigar do sol e receber\u00e3o \u00e1gua e alimento; a instala\u00e7\u00e3o de dez tendas em pontos estrat\u00e9gicos, das 10h \u00e0s 16h, com fornecimento de \u00e1gua e frutas, al\u00e9m de espa\u00e7o pet; refor\u00e7o na compra de ventiladores em unidades de acolhimento; e disponibiliza\u00e7\u00e3o de uma ambul\u00e2ncia referenciada para atendimento a casos de exposi\u00e7\u00e3o ao calor para atender essas tendas.<\/p>\n\n\n\n<p>As tendas estar\u00e3o abertas para acolhimento de qualquer pessoa que queira um abrigo com temperatura amena para descansar e se hidratar. Cada tenda tamb\u00e9m contar\u00e1 tamb\u00e9m com uma ambul\u00e2ncia para eventuais atendimentos relacionados \u00e0 sa\u00fade.<\/p>\n\n\n\n<p>A intensifica\u00e7\u00e3o da infraestrutura da rede de acolhimento da cidade de S\u00e3o Paulo e a abordagem das pessoas em situa\u00e7\u00e3o de vulnerabilidade para que elas possam se proteger tem o objetivo de evitar insola\u00e7\u00e3o, desidrata\u00e7\u00e3o e outros problemas que podem decorrer da exposi\u00e7\u00e3o ao sol forte e altas temperaturas, anunciou a prefeitura.<\/p>\n\n\n\n<p>Fonte: METSUL Meteorologia<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Temperatura no domingo (24.09.23) e no come\u00e7o da semana que vem ser\u00e1 extrema. Calor ter\u00e1 uma escalada nos pr\u00f3ximos dias. [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-301","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/301\/revisions"}],"predecessor-version":[{"id":302,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/301\/revisions\/302"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}