{"id":330,"date":"2023-10-16T09:16:40","date_gmt":"2023-10-16T12:16:40","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=330"},"modified":"2023-10-16T09:29:21","modified_gmt":"2023-10-16T12:29:21","slug":"novo-rg-sera-obrigatorio-no-pais-veja-as-regras","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/novo-rg-sera-obrigatorio-no-pais-veja-as-regras\/","title":{"rendered":"Novo RG ser\u00e1 obrigat\u00f3rio no pa\u00eds. Veja as regras."},"content":{"rendered":"\n<p><strong>A partir de 2032, o novo RG ser\u00e1 obrigat\u00f3rio em todo o pa\u00eds<\/strong>.<\/p>\n\n\n\n<p>O Governo Federal lan\u00e7ou em mar\u00e7o de 2022 a Carteira de Identidade Nacional (CIN), tamb\u00e9m chamada de novo RG. O brasileiro precisa ficar atento \u00e0s mudan\u00e7as que v\u00e3o acontecer.<\/p>\n\n\n\n<p><strong>At\u00e9 o momento, somente alguns estados est\u00e3o emitindo o novo RG:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acre, Alagoa, Amazonas, Goi\u00e1s, Mato Grosso, Minas Gerais, Pernambuco, Piau\u00ed, Paran\u00e1, Rio de Janeiro, Rio Grande do Sul, Santa Catarina.<\/li>\n<\/ul>\n\n\n\n<p><strong>O novo RG ser\u00e1 obrigat\u00f3rio em todo o pa\u00eds<\/strong><\/p>\n\n\n\n<p>A partir de 2032, o novo RG ser\u00e1 obrigat\u00f3rio em todo o pa\u00eds, deixando de valer a vers\u00e3o antiga. Dever\u00e1 acontecer uma troca gradual do documento, sendo feita de uma forma tranquila para que as pessoas possam regularizar o documento quando o antigo perder a validade.<\/p>\n\n\n\n<p>De acordo com o governo, h\u00e1 uma exce\u00e7\u00e3o dessa obriga\u00e7\u00e3o. Quem tiver mais de 60 anos de idade ou mais n\u00e3o precisar\u00e3o atualizar o documento. A vers\u00e3o antiga continuar\u00e1 sendo aceita como v\u00e1lida, sem prazo para expirar.<\/p>\n\n\n\n<p><strong>Como tirar o novo RG (CIN)<\/strong><\/p>\n\n\n\n<p>Para que voc\u00ea possa tirar o novo RG, ser\u00e1 preciso ir as unidades de seguran\u00e7a e institutos de identifica\u00e7\u00e3o (mesmos locais onde eram feitas as vers\u00f5es antigas). Ao chegar na unidade, voc\u00ea dever\u00e1 apresentar a sua certid\u00e3o de nascimento ou casamento. Ser\u00e3o aceitos os documentos impressos ou digitais.<\/p>\n\n\n\n<p>Mas voc\u00ea s\u00f3 poder\u00e1 ter acesso ao novo documento se o seu CPF estiver regularizado. Isso porque o CPF passar\u00e1 a ser o \u00fanico n\u00famero de identifica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em casos que o CPF n\u00e3o esteja regularizado, basta ir a um representante dos Correios ou fazer a regulariza\u00e7\u00e3o pelo site da Receita Federal.<\/p>\n\n\n\n<p>Quem ainda n\u00e3o possui as digitais registradas no sistema do governo precisar\u00e1 passar pelo processo de biometria. As pessoas que atualizaram o t\u00edtulo de eleitor j\u00e1 est\u00e3o cadastrados. Voc\u00ea n\u00e3o precisar\u00e1 pagar nenhuma taxa para emitir o novo RG.<\/p>\n\n\n\n<p><strong>Veja as mudan\u00e7as que v\u00e3o acontecer<\/strong><\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao modelo antigo, a nova vers\u00e3o do RG contar\u00e1 com diversas modifica\u00e7\u00f5es. Confira:<\/p>\n\n\n\n<p><strong><em>Unifica\u00e7\u00e3o com o CPF<\/em><\/strong><\/p>\n\n\n\n<p>O CPF passar\u00e1 a ser utilizado como o n\u00famero de identidade. A unifica\u00e7\u00e3o se deve ao fato de o CPF ser um sistema federal e mais seguro. Antes voc\u00ea tinha que ter o n\u00famero de CPF e tamb\u00e9m o Registro Geral (RG). Isso na pr\u00e1tica, fazia a pessoa ter 27 documentos diferentes, facilitando fraudes.<\/p>\n\n\n\n<p><strong>Validade do documento<\/strong><\/p>\n\n\n\n<p>O documento de identidade passar\u00e1 a ter validade, conforme padr\u00f5es internacionais. O prazo ser\u00e1 de acordo com a idade da pessoa.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>0 a 12 anos: validade pelo per\u00edodo de cinco anos;<\/li>\n\n\n\n<li>12 a 60 anos: validade pelo per\u00edodo de dez anos;<\/li>\n\n\n\n<li>A partir de 60 anos: validade por tempo indeterminado.<\/li>\n<\/ul>\n\n\n\n<p><strong>QR Code e documento digital<\/strong><\/p>\n\n\n\n<p>A Carteira de Identidade Nacional (CIN) tamb\u00e9m ter\u00e1 uma vers\u00e3o digital, semelhante ao que ocorre com a Carteira Digital de Tr\u00e2nsito (dispon\u00edvel para Android e iOS). Isso ser\u00e1 poss\u00edvel gra\u00e7as \u00e0 presen\u00e7a de um QR Code. Al\u00e9m de dar seguran\u00e7a, a ferramenta permite a vers\u00e3o por app. <\/p>\n\n\n\n<p><strong>C\u00f3digo MRZ e outros itens de seguran\u00e7a<\/strong><\/p>\n\n\n\n<p>Vai estar inclu\u00eddo no novo RG, o c\u00f3digo MRZ (Machine Readable Zone) estar\u00e1 inclu\u00eddo no novo RG. Que j\u00e1 \u00e9 utilizada em documentos de passaporte. O RG tamb\u00e9m contar\u00e1 com outros recursos de seguran\u00e7a como marcas d\u2019\u00e1gua.<\/p>\n\n\n\n<p>O MRZ (Machine Readable Zone ou Zona Leg\u00edvel por M\u00e1quina) \u00e9 um c\u00f3digo presente em uma \u00e1rea espec\u00edfica em diversos documentos de identifica\u00e7\u00e3o e cont\u00e9m dados pessoais do titular que s\u00f3 podem ser lidos por uma m\u00e1quina.<\/p>\n\n\n\n<p>Fonte:<a href=\"https:\/\/www.jornalcontabil.com.br\/novo-rg-sera-obrigatorio-no-pais-veja-as-regras\/\"> Jornal Cont\u00e1bil<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 2032, o novo RG ser\u00e1 obrigat\u00f3rio em todo o pa\u00eds. O Governo Federal lan\u00e7ou em mar\u00e7o de [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-330","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":3,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"predecessor-version":[{"id":334,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/330\/revisions\/334"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}