{"id":348,"date":"2023-10-20T08:59:43","date_gmt":"2023-10-20T11:59:43","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=348"},"modified":"2023-10-20T08:59:44","modified_gmt":"2023-10-20T11:59:44","slug":"fgts-nova-regra-do-saque-aniversario-e-definida-e-muda-beneficio-definitivamente","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/fgts-nova-regra-do-saque-aniversario-e-definida-e-muda-beneficio-definitivamente\/","title":{"rendered":"FGTS: Nova regra do saque-anivers\u00e1rio \u00e9 definida e muda benef\u00edcio definitivamente."},"content":{"rendered":"\n<p><strong>Veja como ser\u00e1 a nova regra do saque-anivers\u00e1rio, e o que mudar\u00e1 para os trabalhadores que aderiram a modalidade.<\/strong><\/p>\n\n\n\n<p>Quatro anos ap\u00f3s a implementa\u00e7\u00e3o deste benef\u00edcio, o cen\u00e1rio se prepara para potenciais altera\u00e7\u00f5es. O Governo Federal est\u00e1 articulando o envio de um novo Projeto de Lei ao Congresso Nacional, com o intuito de modificar as diretrizes dessa modalidade, introduzindo mais uma alternativa de acesso aos recursos para os trabalhadores. Vamos explorar, detalhadamente, as iminentes normativas que podem redefinir os procedimentos de retirada de valores do FGTS.<\/p>\n\n\n\n<p><strong>Regras atuais do saque-anivers\u00e1rio<\/strong><\/p>\n\n\n\n<p>Estabelecido pela Lei 13.932\/19, o Saque-Anivers\u00e1rio do FGTS possibilita que o empregado tenha a oportunidade de retirar uma por\u00e7\u00e3o do saldo de sua conta do FGTS todo ano, no m\u00eas em que comemora seu anivers\u00e1rio.<\/p>\n\n\n\n<p>A escolha de aderir ao Saque-Anivers\u00e1rio \u00e9 volunt\u00e1ria. Aqueles que decidirem n\u00e3o aderir continuar\u00e3o no sistema tradicional, denominado Saque-Rescis\u00e3o. \u00c9 fundamental, como alerta a CAIXA, entender as especificidades de cada modalidade ao escolher o Saque-Anivers\u00e1rio:<\/p>\n\n\n\n<p>Saque-Rescis\u00e3o: Este \u00e9 o modelo padr\u00e3o do FGTS no qual o empregado, se dispensado sem justa causa, possui o direito de efetuar o saque total do saldo de sua conta do FGTS, juntamente com a multa rescis\u00f3ria, se aplic\u00e1vel.<\/p>\n\n\n\n<p>Saque-Anivers\u00e1rio: Esta modalidade, de ades\u00e3o facultativa, permite que, anualmente, no m\u00eas de seu anivers\u00e1rio, o empregado possa retirar uma fra\u00e7\u00e3o de seu saldo do FGTS. Se o empregado vier a ser demitido, ter\u00e1 direito apenas ao valor da multa rescis\u00f3ria, sem possibilidade de sacar o valor integral acumulado na conta.<\/p>\n\n\n\n<p><strong>Nova regra do saque-anivers\u00e1rio<\/strong><\/p>\n\n\n\n<p>A recente altera\u00e7\u00e3o na norma do saque-anivers\u00e1rio possibilitar\u00e1 que o empregado com registro em carteira tenha acesso ao montante total do FGTS, assim como ao pagamento da multa rescis\u00f3ria, no cen\u00e1rio de um desligamento sem justa causa.<\/p>\n\n\n\n<p>Vale destacar que a determina\u00e7\u00e3o se aplica de forma retroativa a partir de abril de 2020. Assim, aqueles que j\u00e1 haviam optado pelo saque-anivers\u00e1rio, e que foram desligados nessa janela de tempo e ficaram impedidos de sacar o FGTS devido \u00e0 norma anterior, agora ter\u00e3o o direito de receber os montantes retidos no FGTS, uma vez que at\u00e9 ent\u00e3o s\u00f3 haviam recebido o correspondente \u00e0 multa rescis\u00f3ria.<\/p>\n\n\n\n<p>Segundo declara\u00e7\u00f5es do ministro Marinho, as revis\u00f5es foram estabelecidas em resposta aos apelos de empregados desligados, ansiosos por acessar o saldo remanescente de FGTS, mas que estavam barrados pelas diretrizes vigentes at\u00e9 ent\u00e3o.<\/p>\n\n\n\n<p>Fonte:<a href=\"https:\/\/www.jornalcontabil.com.br\/nova-regra-do-saque-aniversario-e-definida-e-muda-beneficio-definitivamente\/\"> Rede Jornal Cont\u00e1bil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja como ser\u00e1 a nova regra do saque-anivers\u00e1rio, e o que mudar\u00e1 para os trabalhadores que aderiram a modalidade. Quatro [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-348","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=348"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/348\/revisions"}],"predecessor-version":[{"id":349,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/348\/revisions\/349"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}