{"id":386,"date":"2023-11-09T09:16:38","date_gmt":"2023-11-09T12:16:38","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=386"},"modified":"2023-11-09T09:16:39","modified_gmt":"2023-11-09T12:16:39","slug":"empresas-querem-menos-home-office","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/empresas-querem-menos-home-office\/","title":{"rendered":"Empresas querem menos home office."},"content":{"rendered":"\n<p>Nos \u00faltimos meses, grandes empresas est\u00e3o voltando cada vez mais para o presencial. Algumas acabaram totalmente com o regime remoto; outras mant\u00e9m o modelo h\u00edbrido, mas com menos dias de home office.<\/p>\n\n\n\n<p>Trabalhadores at\u00e9 concordam que o regime h\u00edbrido \u00e9 o melhor modelo de trabalho. No Brasil, 76% afirma que este \u00e9 o regime ideal, segundo uma pesquisa da consultoria Robert Half.<\/p>\n\n\n\n<p>Mas h\u00e1 um ponto de discord\u00e2ncia entre empresas e empregados: quantos dias devem ser trabalhados de casa. Virou cabo de guerra.<\/p>\n\n\n\n<p>Trabalhadores querem mais dias de home office, e empresas, menos. Isso se repete no mundo todo.<\/p>\n\n\n\n<p>No Brasil, por exemplo, empregados querem em m\u00e9dia 2,5 dias em home office, enquanto companhias est\u00e3o dispostas a oferecer pouco mais de um dia.<\/p>\n\n\n\n<p>Nos EUA, funcion\u00e1rio querem um pouco mais de 2,5 dias remotos, enquanto empresas cedem 2 dias.<\/p>\n\n\n\n<p>Os n\u00fameros s\u00e3o quebrados porque se tratam de m\u00e9dias. Os dados s\u00e3o da WFH Research, um grupo de pesquisa sobre o trabalho remoto liderado por Nicholas Bloom, da Universidade Stanford.<\/p>\n\n\n\n<p>No Brasil, dados da consultoria de recrutamento Robert Half confirmam a resist\u00eancia dos profissionais ao retorno integral, 38% afirmam que buscariam outro emprego caso o atual decretasse a volta definitiva ao presencial.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/vocesa.abril.com.br\/carreira\/e-o-fim-do-home-office-entenda-o-declinio-do-trabalho-remoto-no-mundo\/\">VC S\/A &#8211; Fim do home office? Entenda o decl\u00ednio do trabalho remoto no mundo<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos \u00faltimos meses, grandes empresas est\u00e3o voltando cada vez mais para o presencial. Algumas acabaram totalmente com o regime remoto; [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-386","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=386"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/386\/revisions"}],"predecessor-version":[{"id":387,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/386\/revisions\/387"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}