{"id":388,"date":"2023-11-10T08:57:34","date_gmt":"2023-11-10T11:57:34","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=388"},"modified":"2023-11-10T09:01:47","modified_gmt":"2023-11-10T12:01:47","slug":"conheca-as-10-principais-mudancas-trabalhistas-e-previdenciarias","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/conheca-as-10-principais-mudancas-trabalhistas-e-previdenciarias\/","title":{"rendered":"Conhe\u00e7a as 10 principais mudan\u00e7as trabalhistas e previdenci\u00e1rias."},"content":{"rendered":"\n<p><strong>S\u00e3o altera\u00e7\u00f5es que afetam a rotina das empresas e envolvem o eSocial, a EFD-Reinf, informa\u00e7\u00f5es de SST, entre outras.<\/strong><\/p>\n\n\n\n<p>As \u00e1reas trabalhista e previdenci\u00e1ria passam por mudan\u00e7as frequentes na legisla\u00e7\u00e3o e exigem acompanhamento constante por parte das empresas.<\/p>\n\n\n\n<p>Neste ano, particularmente, v\u00e1rias regras foram alteradas e novas implementadas e os empregadores devem estar atentos ao seu cumprimento sob o risco de pagarem multas, impactando seus neg\u00f3cios.<\/p>\n\n\n\n<p>Recentemente, por exemplo, o Supremo Tribunal Federal (STF) decidiu que \u00e9 constitucional a cobran\u00e7a da contribui\u00e7\u00e3o assistencial para todos os empregados, incluindo os n\u00e3o sindicalizados.<\/p>\n\n\n\n<p>Para ter validade, a contribui\u00e7\u00e3o deve ser institu\u00edda por meio de conven\u00e7\u00e3o ou acordo coletivo, mas o trabalhador tem o direito de se opor \u00e0 cobran\u00e7a.<\/p>\n\n\n\n<p>Caso n\u00e3o haja oposi\u00e7\u00e3o por escrito, os empregadores passam a ser obrigados a descontar o valor da contribui\u00e7\u00e3o assistencial na folha de pagamento, com base em percentual sobre o sal\u00e1rio definido em conven\u00e7\u00e3o ou acordo coletivo.<\/p>\n\n\n\n<p>Com a decis\u00e3o do STF, as empresas devem ficar atentas e orientar os funcion\u00e1rios sobre o direito de oposi\u00e7\u00e3o ou a possibilidade de desconto obrigat\u00f3rio na folha de sal\u00e1rios, al\u00e9m de acompanhar os desdobramentos do entendimento da Corte junto ao departamento jur\u00eddico.<\/p>\n\n\n\n<p>Mas n\u00e3o foi s\u00f3 isso que mudou. Um levantamento feito pela Domingues e Pinho Contadores mostra as 10 principais altera\u00e7\u00f5es na legisla\u00e7\u00e3o que devem mudar a rotina das empresas. Confira:<\/p>\n\n\n\n<p><strong>1- eSocial<\/strong><\/p>\n\n\n\n<p>A partir da compet\u00eancia de outubro, os empregadores passam a ser obrigados a incluir as informa\u00e7\u00f5es relativas a processos trabalhistas no eSocial.<\/p>\n\n\n\n<p>O prazo para o envio dos dados ao sistema \u00e9 at\u00e9 o dia 15 do m\u00eas subsequente \u00e0 data relativa \u00e0 conclus\u00e3o dos processos trabalhistas com tr\u00e2nsito em julgado, homologa\u00e7\u00e3o de acordos e determina\u00e7\u00f5es judiciais.<\/p>\n\n\n\n<p><strong>2- Mudan\u00e7as na EFD-Reinf<\/strong><\/p>\n\n\n\n<p>A EFD-Reinf, um dos m\u00f3dulos do SPED (Sistema P\u00fablico de Escritura\u00e7\u00e3o Digital), est\u00e1 em processo de mudan\u00e7a, com a entrada dos tributos federais retidos na fonte a partir da compet\u00eancia de setembro de 2023. Este movimento faz parte da transi\u00e7\u00e3o da Dirf, que ser\u00e1 extinta em 2025, para a EFD-Reinf.<\/p>\n\n\n\n<p>O eSocial e EFD-Reinf, ap\u00f3s sua transmiss\u00e3o, abastecem automaticamente a DCTFWeb, que a partir desta mudan\u00e7a passar\u00e1 a emitir guia \u00fanica para o recolhimento de todos esses tributos.<\/p>\n\n\n\n<p>Essa unifica\u00e7\u00e3o vai exigir das empresas o alinhamento das informa\u00e7\u00f5es tribut\u00e1rias, trabalhistas e previdenci\u00e1rias.<\/p>\n\n\n\n<p><strong>3- FGTS digital<\/strong><\/p>\n\n\n\n<p>A implementa\u00e7\u00e3o do FGTS Digital est\u00e1 prevista para janeiro de 2024, mas o novo sistema j\u00e1 est\u00e1 operando em modo teste, dispon\u00edvel para os empregadores. A novidade ir\u00e1 substituir o Sefip na gera\u00e7\u00e3o de guias de recolhimento da contribui\u00e7\u00e3o mensal ou rescis\u00f3ria.<\/p>\n\n\n\n<p>Um dos pontos de aten\u00e7\u00e3o \u00e9 a altera\u00e7\u00e3o do prazo de recolhimento do FGTS mensal para at\u00e9 o 20\u00ba dia do m\u00eas seguinte ao da compet\u00eancia. Mas at\u00e9 que a ferramenta esteja implementada, continua valendo o 7\u00ba dia do m\u00eas seguinte ao da compet\u00eancia.<\/p>\n\n\n\n<p><strong>4- Igualdade salarial<\/strong><\/p>\n\n\n\n<p>A Lei n\u00ba 14.611\/2023 entrou em vigor em julho, trazendo novas regras relativas \u00e0 igualdade salarial entre mulheres e homens e formas de combate \u00e0 discrimina\u00e7\u00e3o nos crit\u00e9rios remunerat\u00f3rios por motivo de sexo, ra\u00e7a, etnia, origem ou idade.<\/p>\n\n\n\n<p>A igualdade deve ser garantida por medidas como a cria\u00e7\u00e3o de canais espec\u00edficos para den\u00fancia, a realiza\u00e7\u00e3o de programas de diversidade e inclus\u00e3o para capacita\u00e7\u00e3o de gestores, l\u00edderes e empregados.<\/p>\n\n\n\n<p>Empresas com 100 empregados ou mais est\u00e3o obrigadas ainda a realizar a publica\u00e7\u00e3o semestral de relat\u00f3rios de transpar\u00eancia salarial e de crit\u00e9rios remunerat\u00f3rios.<\/p>\n\n\n\n<p><strong>5- Dados \u00e9tnico-raciais<\/strong><\/p>\n\n\n\n<p>Desde abril, empregadores est\u00e3o obrigados a incluir os dados \u00e9tnico-raciais em fichas de admiss\u00e3o, demiss\u00e3o e formul\u00e1rios de acidente de trabalho.<\/p>\n\n\n\n<p>Esses registros e documentos trabalhistas devem conter um campo destinado \u00e0 identifica\u00e7\u00e3o \u00e9tnico-racial dos funcion\u00e1rios, preenchido segundo o crit\u00e9rio da autoclassifica\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>6- Combate a ass\u00e9dio e viol\u00eancia<\/strong><\/p>\n\n\n\n<p>As empresas que contam com Comiss\u00e3o Interna de Preven\u00e7\u00e3o de Acidentes e de Ass\u00e9dio (CIPAA) possuem uma s\u00e9rie de obriga\u00e7\u00f5es a serem cumpridas.<\/p>\n\n\n\n<p>Desde mar\u00e7o de 2023, conforme determina a Portaria n\u00ba 4.219\/2022, essas empresas devem adotar medidas para preven\u00e7\u00e3o e combate ao ass\u00e9dio sexual e demais formas de viol\u00eancia no \u00e2mbito do trabalho.<\/p>\n\n\n\n<p><strong>7- Obriga\u00e7\u00f5es de SST<\/strong><\/p>\n\n\n\n<p>Desde janeiro de 2023, os empregadores est\u00e3o obrigados a enviar dados de Sa\u00fade e Seguran\u00e7a do Trabalho (SST) ao eSocial, sob o risco de pagarem multas.<\/p>\n\n\n\n<p>Por meio desses eventos de SST s\u00e3o cumpridas obriga\u00e7\u00f5es referentes \u00e0 emiss\u00e3o da CAT, elabora\u00e7\u00e3o e atualiza\u00e7\u00e3o do Perfil Profissiogr\u00e1fico Previdenci\u00e1rio, acompanhamento da sa\u00fade do trabalhador e informa\u00e7\u00f5es sobre exposi\u00e7\u00e3o do funcion\u00e1rio a agentes nocivos para fins de aposentadoria especial.<\/p>\n\n\n\n<p><strong>8- Portabilidade do vale-refei\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Publicado em agosto, o Decreto 11.678\/2023 trata da portabilidade do vale-refei\u00e7\u00e3o e vale-alimenta\u00e7\u00e3o relativos ao Programa de Alimenta\u00e7\u00e3o do Trabalhador (PAT).<\/p>\n\n\n\n<p>O novo modelo deve ampliar a concorr\u00eancia no setor, dando mais liberdade para que os trabalhadores escolham a empresa gestora desse benef\u00edcio.<\/p>\n\n\n\n<p>O texto tamb\u00e9m estabelece obriga\u00e7\u00e3o de as empresas benefici\u00e1rias do PAT disporem de programas destinados a promover e monitorar a sa\u00fade e a aprimorar a seguran\u00e7a alimentar e nutricional de seus trabalhadores.<\/p>\n\n\n\n<p><strong>9- Fator Acident\u00e1rio de Preven\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>O Fator Acident\u00e1rio de Preven\u00e7\u00e3o (FAP) \u00e9 um multiplicador que incide sobre a folha de sal\u00e1rios para custear benef\u00edcios decorrentes de acidentes de trabalho e aposentadorias especiais.<\/p>\n\n\n\n<p>Como o FAP traz impactos no valor das contribui\u00e7\u00f5es previdenci\u00e1rias das empresas, \u00e9 importante verificar o \u00edndice atribu\u00eddo pelo governo, que foi publicado em 30 de setembro.<\/p>\n\n\n\n<p>Caso a empresa n\u00e3o concorde com o valor atribu\u00eddo, \u00e9 poss\u00edvel questionar e recorrer at\u00e9 o final de novembro.<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 importante saber que o sistema para consulta, contesta\u00e7\u00e3o e recurso agora \u00e9 feito por meio do Gov.br e n\u00e3o mais pela senha cadastrada na Receita Federal.<\/p>\n\n\n\n<p><strong>10- Informa\u00e7\u00f5es sobre plano de sa\u00fade<\/strong><\/p>\n\n\n\n<p>Uma mudan\u00e7a operacional importante que est\u00e1 em curso diz respeito \u00e0s informa\u00e7\u00f5es sobre pagamentos efetuados a planos privados de assist\u00eancia \u00e0 sa\u00fade, na modalidade coletivo empresarial como benef\u00edcio dos empregados, hoje feita por meio da Dirf.<\/p>\n\n\n\n<p>Com essa declara\u00e7\u00e3o sendo extinta em 2024, \u00e9 necess\u00e1rio ter aten\u00e7\u00e3o \u00e0 nova forma de presta\u00e7\u00e3o das informa\u00e7\u00f5es sobre planos de sa\u00fade, ainda a ser definida pela Receita Federal.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/fenacon.org.br\/noticias\/conheca-as-10-principais-mudancas-trabalhistas-e-previdenciarias\/\">FENACON<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o altera\u00e7\u00f5es que afetam a rotina das empresas e envolvem o eSocial, a EFD-Reinf, informa\u00e7\u00f5es de SST, entre outras. As [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-388","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":2,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/388\/revisions"}],"predecessor-version":[{"id":390,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/388\/revisions\/390"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}