{"id":428,"date":"2023-12-06T09:33:30","date_gmt":"2023-12-06T12:33:30","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=428"},"modified":"2023-12-06T09:33:49","modified_gmt":"2023-12-06T12:33:49","slug":"entenda-como-vai-funcionar-nova-regra-de-feriados-em-2024-veja-setores-afetados","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/entenda-como-vai-funcionar-nova-regra-de-feriados-em-2024-veja-setores-afetados\/","title":{"rendered":"Entenda como vai funcionar nova regra de feriados em 2024; veja setores afetados."},"content":{"rendered":"\n<p><strong>Nova portaria estabelece que trabalho no feriado s\u00f3 ser\u00e1 permitido com conven\u00e7\u00e3o coletiva.<\/strong><\/p>\n\n\n\n<p>A partir de mar\u00e7o de 2024, a regra para trabalhar no feriado muda. Com a nova portaria, publicada no dia 13 de novembro, o trabalho nos feriados somente ser\u00e1 permitido se houver previs\u00e3o em conven\u00e7\u00e3o coletiva da categoria e observada a lei municipal. Para os domingos, se existir lei municipal autorizando o funcionamento, n\u00e3o h\u00e1 necessidade da norma coletiva.<\/p>\n\n\n\n<p>Antes, n\u00e3o era necess\u00e1rio o acordo. A portaria anterior, de n\u00b0 617, publicada durante o governo do ex-presidente Jair Bolsonaro, determinava que o empregador poderia comunicar aos funcion\u00e1rios que o estabelecimento abriria normalmente e a escala de trabalho, respeitando os direitos de folga.<\/p>\n\n\n\n<p>O Ministro do Trabalho e Emprego, Luiz Marinho, revogou a antiga portaria e anunciou que quer retomar a negocia\u00e7\u00e3o entre trabalhadores e empregadores.<\/p>\n\n\n\n<p>Com a nova portaria, diversas atividades comerciais que tinham autoriza\u00e7\u00e3o para trabalhar nos feriados ficam revogadas.<\/p>\n\n\n\n<p>N\u00e3o t\u00eam mais autoriza\u00e7\u00e3o para trabalhar nos feriados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>varejistas de peixe;<\/li>\n\n\n\n<li>varejistas de carnes frescas e ca\u00e7a;<\/li>\n\n\n\n<li>varejistas de frutas e verduras;<\/li>\n\n\n\n<li>varejistas de aves e ovos;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>varejistas de produtos farmac\u00eauticos (farm\u00e1cias, inclusive manipula\u00e7\u00e3o de receitu\u00e1rio);<\/li>\n\n\n\n<li>revoga\u00e7\u00e3o parcial apenas das atividades de: mercados, com\u00e9rcio varejista de supermercados e de hipermercados, cuja atividade preponderante seja a venda de alimentos, inclusive os transportes a eles inerentes;<\/li>\n\n\n\n<li>com\u00e9rcio em hot\u00e9is;<\/li>\n\n\n\n<li>com\u00e9rcio em geral;<\/li>\n\n\n\n<li>atacadistas e distribuidores de produtos industrializados;<\/li>\n\n\n\n<li>revendedores de tratores, caminh\u00f5es, autom\u00f3veis e ve\u00edculos similares.<\/li>\n<\/ul>\n\n\n\n<p>Apesar de a permiss\u00e3o de trabalho nesses dias j\u00e1 estar prevista em lei espec\u00edfica, o setor de com\u00e9rcio voltar\u00e1 a depender de conven\u00e7\u00f5es coletivas e legisla\u00e7\u00e3o municipal para colocar seus funcion\u00e1rios para trabalhar em domingos e feriados.<\/p>\n\n\n\n<p><strong>Acordo pr\u00e9vio coletivo <\/strong><\/p>\n\n\n\n<p>Na semana passada, uma portaria do Minist\u00e9rio do Trabalho determinou a necessidade de acordo pr\u00e9vio coletivo conduzido por sindicatos para que lojas possam abrir em feriados, o que provocou forte rea\u00e7\u00e3o negativa de entidades ligadas ao com\u00e9rcio e uma mobiliza\u00e7\u00e3o no Congresso para a derrubada da decis\u00e3o com um decreto legislativo.<\/p>\n\n\n\n<p>Marinho decidiu ent\u00e3o se antecipar a esse movimento e suspender a medida. Segundo ele, houve entendimento errado da portaria, que ir\u00e1 restringir apenas os feriados a novos crit\u00e9rios, e n\u00e3o os domingos. Uma nota ser\u00e1 divulgada pelo minist\u00e9rio com mais detalhes sobre a decis\u00e3o.<\/p>\n\n\n\n<p>&#8220;Estamos falando de portaria que regula processo de funcionamento do com\u00e9rcio aos feriados, t\u00e3o somente. Ela \u00e9 clara e transparente, os domingos est\u00e3o legislados por lei. Uma portaria de 2021, essa sim contrariando a lei, deu entendimento de que os feriados tamb\u00e9m n\u00e3o teriam necessidade [de acordo coletivo pr\u00e9vio com sindicatos] e o patr\u00e3o da loja poderia na v\u00e9spera falar para [o empregado] ir trabalhar&#8221;, afirmou.<\/p>\n\n\n\n<p>O ministro voltou a reafirmar que o trabalho aos feriados precisa ser regulado, mas que o grupo de trabalho com representantes do governo, trabalhadores e entidades empresariais ir\u00e1 ajudar na defini\u00e7\u00e3o do novo texto.<\/p>\n\n\n\n<p><strong>O que o com\u00e9rcio prop\u00f5e? <\/strong><\/p>\n\n\n\n<p>Empres\u00e1rios do com\u00e9rcio devem propor ao governo federal que a nova reda\u00e7\u00e3o da portaria que limita o trabalho no setor nos feriados tenha regras espec\u00edficas para estabelecimentos considerados essenciais. Eles pretendem atuar no grupo de trabalho que vai discutir o conte\u00fado de uma nova vers\u00e3o do texto, para entrar em vigor em mar\u00e7o.<\/p>\n\n\n\n<p>De acordo com o vice-presidente administrativo da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio (CNC), Antonio Florencio de Queiroz Junior, a entidade levou ao governo a proposta de postergar por 90 dias a entrada em vigor da publica\u00e7\u00e3o, para que ajustes sejam feitos.<\/p>\n\n\n\n<p>Ele diz que uma das prioridades \u00e9 que o texto seja mais espec\u00edfico sobre o funcionamento de estabelecimentos essenciais, como farm\u00e1cias, supermercados, postos de gasolina e hot\u00e9is.<\/p>\n\n\n\n<p>&#8220;Esses estabelecimentos t\u00eam caracter\u00edsticas muito espec\u00edficas. A legisla\u00e7\u00e3o de funcionamento de feriados j\u00e1 existe e \u00e9 pacificada no setor. Mas a portaria esqueceu dessas caracter\u00edsticas e criou um problema para esses setores. N\u00e3o defendemos a derrubada da publica\u00e7\u00e3o, porque n\u00e3o vimos necessidade. Os ajustes j\u00e1 s\u00e3o suficientes&#8221;, afirma.<\/p>\n\n\n\n<p>O presidente da Fecomercio-RJ, Queiroz Junior, tamb\u00e9m afirmou que a primeira reuni\u00e3o do grupo de trabalho \u2014 com representantes do governo, trabalhadores e entidades empresariais \u2014 deve acontecer j\u00e1 na pr\u00f3xima quarta-feira, dia 29, na cidade do Rio.<\/p>\n\n\n\n<p>Um dos argumentos dos empres\u00e1rios foi a inseguran\u00e7a jur\u00eddica trazida pela publica\u00e7\u00e3o. Ainda de acordo com Queiroz Junior, em reuni\u00e3o com o governo, o setor ponderou que a necessidade de conven\u00e7\u00e3o coletiva entre os sindicatos dos trabalhadores e o patronal tratando do trabalho nos feriados seria um impasse em estados como o Acre e o Amazonas, onde, segundo ele, n\u00e3o existem entidades representativas dos trabalhadores do com\u00e9rcio.<\/p>\n\n\n\n<p>Ele aponta como sa\u00edda que o novo texto da portaria crie alternativas para a negocia\u00e7\u00e3o:<\/p>\n\n\n\n<p>&#8220;O Brasil \u00e9 um pa\u00eds de dimens\u00f5es continentais. Algumas regi\u00f5es t\u00eam realidades econ\u00f4micas e de negocia\u00e7\u00e3o muito diferentes. No Rio e em S\u00e3o Paulo, por exemplo, o impacto n\u00e3o seria t\u00e3o grande porque j\u00e1 existem nas conven\u00e7\u00f5es coletiva as regras de trabalho nos feriados, mas isso n\u00e3o ocorre em outros locais. Um caminho pode ser permitir que federa\u00e7\u00f5es e confedera\u00e7\u00f5es firmem as conven\u00e7\u00f5es nos locais que n\u00e3o tenham o sindicado laboral&#8221;.<\/p>\n\n\n\n<p>O presidente da Associa\u00e7\u00e3o Brasileira de Supermercados (Abras), Jo\u00e3o Galassi, defendeu que atividades essenciais n\u00e3o devem ser reguladas atrav\u00e9s de acordos coletivos.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/exame.com\/brasil\/entenda-como-vai-funcionar-nova-regra-de-feriados-em-2024-veja-setores-afetados\/\">Site Exame<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova portaria estabelece que trabalho no feriado s\u00f3 ser\u00e1 permitido com conven\u00e7\u00e3o coletiva. A partir de mar\u00e7o de 2024, a [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-428","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=428"}],"version-history":[{"count":2,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/428\/revisions"}],"predecessor-version":[{"id":430,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/428\/revisions\/430"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}