{"id":439,"date":"2023-12-28T08:45:43","date_gmt":"2023-12-28T11:45:43","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=439"},"modified":"2023-12-28T08:45:44","modified_gmt":"2023-12-28T11:45:44","slug":"simples-nacional-resolucao-174-altera-regras","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/simples-nacional-resolucao-174-altera-regras\/","title":{"rendered":"Simples Nacional: Resolu\u00e7\u00e3o 174 altera regras."},"content":{"rendered":"\n<p><strong>Resolu\u00e7\u00e3o n\u00ba 174 do Comit\u00ea Gestor altera regras do Simples Nacional, novidade reduz multas por infra\u00e7\u00e3o praticadas pela ME e EPP benefici\u00e1ria do regime.<\/strong><\/p>\n\n\n\n<p>Resolu\u00e7\u00e3o n\u00ba 174 de 2023 do Comit\u00ea Gestor do Simples Nacional (DOU de 15.12.23), altera a Resolu\u00e7\u00e3o CGSN n\u00ba 140 de 2018, que disp\u00f5e sobre o Regime Especial Unificado de Arrecada\u00e7\u00e3o de Tributos e Contribui\u00e7\u00f5es devidos pelas Microempresas e Empresas de Pequeno Porte (Simples Nacional).<\/p>\n\n\n\n<p><strong>Altera\u00e7\u00f5es relevantes trazidas pela Resolu\u00e7\u00e3o CGSN n\u00ba 174\/2023: <\/strong><\/p>\n\n\n\n<p><strong>1 \u2013 Amplia\u00e7\u00e3o do prazo de recolhimento do FGTS devido pelo MEI<\/strong>.<\/p>\n\n\n\n<p>Para atender o FGTS digital, a Resolu\u00e7\u00e3o n\u00ba 174\/2023 do Comit\u00ea Gestor atualizou o prazo de recolhimento devido pelo MEI, do dia 07 para o dia 20 m\u00eas subsequente (observando a regra da antecipa\u00e7\u00e3o quando cair em dia n\u00e3o \u00fatil).<\/p>\n\n\n\n<p><strong> 2 \u2013 Redu\u00e7\u00e3o de multas por infra\u00e7\u00e3o aplic\u00e1veis \u00e0s microempresas e empresas de pequeno porte, optantes pelo Simples Nacional.<\/strong><\/p>\n\n\n\n<p>Confira os dispositivos da Resolu\u00e7\u00e3o CGSN n\u00ba 140 de 2018, alterados pela Resolu\u00e7\u00e3o CGSN n\u00ba 174\/2023:<\/p>\n\n\n\n<p><strong>Art. 27<\/strong> \u2013 trata da reten\u00e7\u00e3o do ISS<\/p>\n\n\n\n<p><strong>Art. 93<\/strong> \u2013 Trata de infra\u00e7\u00e3o<\/p>\n\n\n\n<p><strong>Art. 96<\/strong> \u2013 Trata do descumprimento da obriga\u00e7\u00e3o principal \u2013 multas<\/p>\n\n\n\n<p><strong>Art. 105-A<\/strong> \u2013 trata do prazo de recolhimento do FGTS pelo MEI, confira:<\/p>\n\n\n\n<p><strong>Nova reda\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Art. 105-A. O MEI dever\u00e1 cumprir as obriga\u00e7\u00f5es de que trata o \u00a7 1\u00ba do art. 105, bem como as relativas ao FGTS, por meio do eSocial, o qual dever\u00e1 gerar um Documento de Arrecada\u00e7\u00e3o do eSocial (DAE). ( Lei Complementar n\u00ba 123, de 2006, art. 18-C, \u00a7\u00a7 1\u00ba e 3\u00ba, inciso II) .<\/p>\n\n\n\n<p>\u00a7 1\u00ba O recolhimento do DAE a que se refere o caput dever\u00e1 ocorrer at\u00e9 o dia 20 (vinte) do m\u00eas subsequente \u00e0quele em que os valores s\u00e3o devidos, com exce\u00e7\u00e3o dos casos referidos no \u00a7 2\u00ba e observado o disposto no \u00a7 4\u00ba. (Lei Complementar n\u00ba 123, de 2006, art. 18-C, \u00a7\u00a7 1\u00ba e 3\u00ba, inciso II).<\/p>\n\n\n\n<p>\u00a7 4\u00ba Quando n\u00e3o houver expediente banc\u00e1rio na data estabelecida no \u00a7 1\u00ba, o recolhimento do valor constante do DAE dever\u00e1 ocorrer at\u00e9 o dia \u00fatil imediatamente anterior.\u201d (NR).<\/p>\n\n\n\n<p><strong>Revogou o art. 97 que trata das multas relacionadas ao DASN \u2013 Declara\u00e7\u00e3o Simplificada da Pessoa Jur\u00eddica, confira:<\/strong><\/p>\n\n\n\n<p>Art. 97. A ME ou EPP que deixar de apresentar a DASN ou que a apresentar com incorre\u00e7\u00f5es ou omiss\u00f5es ou, ainda, que a apresentar fora do prazo fixado, ser\u00e1 intimada a apresent\u00e1-la ou a prestar esclarecimentos, conforme o caso, no prazo estipulado pela autoridade fiscal, e sujeitar-se-\u00e1 a multa: (Lei Complementar n\u00ba 123, de 2006, art. 38).<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/sigaofisco.com.br\/simples-nacional-resolucao-174-altera-regras\/\">Site Siga o Fisco<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolu\u00e7\u00e3o n\u00ba 174 do Comit\u00ea Gestor altera regras do Simples Nacional, novidade reduz multas por infra\u00e7\u00e3o praticadas pela ME e [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-439","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"predecessor-version":[{"id":440,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/439\/revisions\/440"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}