{"id":595,"date":"2024-08-12T09:20:04","date_gmt":"2024-08-12T12:20:04","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=595"},"modified":"2024-08-12T09:20:05","modified_gmt":"2024-08-12T12:20:05","slug":"empresas-precisam-se-preparar-para-os-impactos-da-reforma-tributaria","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/empresas-precisam-se-preparar-para-os-impactos-da-reforma-tributaria\/","title":{"rendered":"Empresas precisam se preparar para os impactos da Reforma Tribut\u00e1ria."},"content":{"rendered":"\n<p><strong>Executivos avaliam poss\u00edveis impactos da reforma nos setores de tecnologia, planos de sa\u00fade, condom\u00ednios, marketing de incentivo e gest\u00e3o empresarial. <\/strong><\/p>\n\n\n\n<p>Foi aprovado pelo plen\u00e1rio da C\u00e2mara dos Deputados o projeto de lei complementar (PLP 68\/2024) que trata da regulamenta\u00e7\u00e3o da reforma tribut\u00e1ria dos impostos sobre o consumo. Este \u00e9 o primeiro projeto de lei complementar que avan\u00e7a sobre a regulamenta\u00e7\u00e3o de pontos tratados na Emenda Constitucional (EC 132\/2023) da reforma tribut\u00e1ria, promulgada pelo Congresso Nacional no fim do ano passado, e que deve entrar em vigor em 2026.<\/p>\n\n\n\n<p>Para Felipe Renault, advogado participante dos Grupos de Trabalho da Reforma Tribut\u00e1ria, o texto representa um grande avan\u00e7o na simplifica\u00e7\u00e3o dos impostos, mas sua preocupa\u00e7\u00e3o \u00e9 com o modelo aprovado. &#8220;Receio que ele gere distor\u00e7\u00f5es econ\u00f4micas e altera\u00e7\u00f5es nas cadeias produtivas em raz\u00e3o da obrigatoriedade de pagamento do tributo para que se gere cr\u00e9dito. Somos o primeiro pa\u00eds do mundo que estabelece o cr\u00e9dito condicionado ao pagamento. No meu entender, isso pode colocar em xeque a efici\u00eancia e todo o lado positivo da reforma&#8221;, diz.<\/p>\n\n\n\n<p>O especialista tem compartilhado seu conhecimento detalhado sobre a reforma tribut\u00e1ria nos eventos da WK, empresa especializada em ERP e gest\u00e3o empresarial com 40 anos no mercado. &#8220;Para os gestores, o grande desafio ser\u00e1 preparar as empresas para o per\u00edodo de transi\u00e7\u00e3o, convivendo com dois regimes tribut\u00e1rios distintos \u2013 o antigo e o novo \u2013 at\u00e9 2033,\u00a0 e adaptando o neg\u00f3cio \u00e0 nova carga tribut\u00e1ria&#8221;, diz. O pr\u00f3ximo encontro ser\u00e1 nos dias 12 e 13 de setembro, durante a segunda edi\u00e7\u00e3o do Conex\u00e3o WK, no Clube Bela Vista em Gaspar\/SC.\u00a0<\/p>\n\n\n\n<p>Confira abaixo como a reforma pode impactar diferentes setores da economia:<\/p>\n\n\n\n<p><strong>Condom\u00ednios dever\u00e3o buscar equil\u00edbrio entre redu\u00e7\u00e3o de custos e pagamento de despesas<\/strong><\/p>\n\n\n\n<p>Os impactos da reforma tribut\u00e1ria no setor de servi\u00e7os devem refletir em outros segmentos &#8211; como o condominial. Como a maior parte das despesas de um condom\u00ednio envolve a contrata\u00e7\u00e3o de prestadores de servi\u00e7os, uma mudan\u00e7a na tributa\u00e7\u00e3o dessa \u00e1rea pode refletir em aumento na taxa condominial &#8211; contribui\u00e7\u00e3o mensal paga pelos propriet\u00e1rios para cobrir despesas comuns. De acordo com o vice-presidente da\u00a0BRCondos,\u00a0Fernando Willrich, s\u00edndicos dever\u00e3o estar preparados para discutir o tema em assembleias e encontrar um equil\u00edbrio entre a necessidade de cobrir os custos com a capacidade de pagamento dos moradores.<\/p>\n\n\n\n<p>\u201cAo mesmo tempo que \u00e9 preciso arcar com gastos como seguran\u00e7a, limpeza e manuten\u00e7\u00e3o predial, o valor repassado aos moradores n\u00e3o pode inviabilizar o pagamento em dia. Se isso ocorrer, o s\u00edndico pode enfrentar outro problema: a inadimpl\u00eancia\u201d, explica Fernando.<\/p>\n\n\n\n<p>De acordo com o executivo, uma alternativa para diminuir os impactos da nova tributa\u00e7\u00e3o \u00e9 a automatiza\u00e7\u00e3o da gest\u00e3o financeira. \u201cSer\u00e1 preciso aumentar a efici\u00eancia dessa gest\u00e3o para repassar com transpar\u00eancia os gastos e arrecada\u00e7\u00f5es do condom\u00ednio. O controle automatizado torna esse processo mais \u00e1gil, o que ajuda na tomada de decis\u00e3o e oferece seguran\u00e7a ao cond\u00f4mino\u201d, conclui.<\/p>\n\n\n\n<p><strong><strong>Nos planos de sa\u00fade, impactos da reforma podem ser mitigados com apoio da tecnologia<\/strong><\/strong><\/p>\n\n\n\n<p>No \u00e2mbito dos planos de sa\u00fade, a preocupa\u00e7\u00e3o est\u00e1 nas novas regras de dedu\u00e7\u00e3o. A nova norma impede que as empresas deduzam os gastos com o plano de sa\u00fade corporativo dos funcion\u00e1rios do c\u00e1lculo do novo IVA, o que deve aumentar os custos para as organiza\u00e7\u00f5es que oferecem esse benef\u00edcio aos colaboradores. Al\u00e9m disso, h\u00e1 o medo de que, com um aumento da tributa\u00e7\u00e3o, haja uma queda nos investimentos em melhorias nos servi\u00e7os, comprometendo sua qualidade.<\/p>\n\n\n\n<p>De acordo com\u00a0Guilhermino Afonso, CEO da\u00a0Wellbe, healthtech de gest\u00e3o corporativa, o uso de solu\u00e7\u00f5es digitais tem despontado como uma alternativa para driblar esses desafios.<\/p>\n\n\n\n<p>&#8220;Destaco tr\u00eas aplica\u00e7\u00f5es tecnol\u00f3gicas que considero essenciais. A primeira, \u00e9 a implementa\u00e7\u00e3o de sistemas de gerenciamento de dados que ajudem a operadora a obter informa\u00e7\u00f5es precisas sobre os pacientes. A segunda, \u00e9 a automatiza\u00e7\u00e3o dos processos, para que haja maior agilidade nos atendimentos e diminui\u00e7\u00e3o de poss\u00edveis erros na opera\u00e7\u00e3o. Finalmente, deve-se investir na ado\u00e7\u00e3o de solu\u00e7\u00f5es digitais que facilitem o acesso \u00e0s informa\u00e7\u00f5es e aos servi\u00e7os de sa\u00fade&#8221;, complementa.<\/p>\n\n\n\n<p><strong>No setor da tecnologia, foco pode se voltar para mercado externo<\/strong><\/p>\n\n\n\n<p>A reforma pode levar as empresas brasileiras de tecnologia a voltarem os seus olhos para o mercado exterior.\u00a0 Com a al\u00edquota interna do futuro IVA m\u00e9dia em 26,5% , a exporta\u00e7\u00e3o dever\u00e1 se tornar mais atrativa e at\u00e9 mesmo um caminho de sobreviv\u00eancia para muitos empreendedores. O alerta \u00e9 do CEO da WTM International, Lisandro Vieira, que tamb\u00e9m atua como conselheiro da Associa\u00e7\u00e3o de Com\u00e9rcio Exterior do Brasil (AEB) e \u00e9 diretor do Grupo Tem\u00e1tico de Internacionaliza\u00e7\u00e3o da Associa\u00e7\u00e3o Catarinense de Tecnologia (ACATE). Segundo ele, \u201cser\u00e1 mais atrativo vender para outro pa\u00eds do que\u00a0 buscar clientes no Brasil\u201d.<\/p>\n\n\n\n<p>Na reforma, o conceito de exporta\u00e7\u00e3o de servi\u00e7os fica mais simplificado, assim como o de importa\u00e7\u00e3o, e todas as mudan\u00e7as devem gerar muita aten\u00e7\u00e3o por parte dos empres\u00e1rios:<\/p>\n\n\n\n<p>\u201cNo regime atual, al\u00e9m das d\u00favidas geradas pela defini\u00e7\u00e3o de exporta\u00e7\u00e3o para ISS e PIS\/COFINS, a imunidade ocorre apenas na \u00faltima fase da cadeia da presta\u00e7\u00e3o de servi\u00e7os. Com a n\u00e3o-cumulatividade de IBS\/CBS prevista na reforma, a tend\u00eancia \u00e9 diminuir o res\u00edduo tribut\u00e1rio da cadeia exportadora de servi\u00e7os. Mas para isso as empresas devem estar atentas aos seus principais insumos, podendo at\u00e9 rever a forma de contrata\u00e7\u00e3o de pessoas e fornecedores\u201d, explica o CFO da WTM International, Lu\u00eds Henrique Dias.<\/p>\n\n\n\n<p><strong>Programas de incentivo tamb\u00e9m podem ter altera\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p>Com a Reforma Tribut\u00e1ria, os projetos desenvolvidos no mercado de Marketing de Incentivo podem necessitar de revis\u00e3o em termos de estrutura fiscal, especialmente ao que se refere ao formato de como pr\u00eamios e bonifica\u00e7\u00f5es s\u00e3o tributados. As\u00a0 altera\u00e7\u00f5es na carga tribut\u00e1ria sobre bens e servi\u00e7os utilizados podem influenciar a escolha e a viabilidade dos programas de incentivo, que s\u00e3o desenvolvidos pelas empresas. Diante da\u00a0 adapta\u00e7\u00e3o \u00e0 nova legisla\u00e7\u00e3o, podem ser necess\u00e1rios novos planejamentos nos programas existentes, incluindo reavalia\u00e7\u00f5es de custos e benef\u00edcios fiscais associados a diferentes formas de recompensa.<\/p>\n\n\n\n<p>No entanto, vale ressaltar que a simplifica\u00e7\u00e3o do sistema tribut\u00e1rio brasileiro abre oportunidade tamb\u00e9m que pode permitir que as empresas implementem programas de incentivo de forma mais eficiente e com menor carga administrativa e compliance tribut\u00e1rio.\u00a0<\/p>\n\n\n\n<p>Daniel Moreira, CEO da Hub4Pay, fintech de pagamentos especializada em premia\u00e7\u00f5es digitais, destaca que a adapta\u00e7\u00e3o a um novo regime tribut\u00e1rio requer n\u00e3o apenas mudan\u00e7as administrativas e financeiras, mas tamb\u00e9m uma gest\u00e3o eficaz do capital humano. &#8220;\u00c9 neste ponto que o marketing de incentivo se evidencia como uma ferramenta poderosa para manter a motiva\u00e7\u00e3o e o engajamento dos colaboradores durante per\u00edodos de transi\u00e7\u00e3o. Programas bem estruturados podem mitigar a incerteza e o estresse, refor\u00e7ando a confian\u00e7a na estabilidade e no crescimento futuro da empresa&#8221;, afirma o executivo.<\/p>\n\n\n\n<p>Fonte:<a href=\"https:\/\/www.contabeis.com.br\/noticias\/66502\/empresas-precisam-se-preparar-para-os-impactos-da-reforma-tributaria\/\"> Cont\u00e1beis<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Executivos avaliam poss\u00edveis impactos da reforma nos setores de tecnologia, planos de sa\u00fade, condom\u00ednios, marketing de incentivo e gest\u00e3o empresarial. [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-595","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=595"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/595\/revisions"}],"predecessor-version":[{"id":596,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/595\/revisions\/596"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}