{"id":770,"date":"2025-01-03T11:31:58","date_gmt":"2025-01-03T14:31:58","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=770"},"modified":"2025-01-03T11:32:00","modified_gmt":"2025-01-03T14:32:00","slug":"nota-eletronica-sera-obrigatoria-para-produtores-rurais-do-rs-com-renda-bruta-superior-a-r-360-mil","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/nota-eletronica-sera-obrigatoria-para-produtores-rurais-do-rs-com-renda-bruta-superior-a-r-360-mil\/","title":{"rendered":"Nota eletr\u00f4nica ser\u00e1 obrigat\u00f3ria para produtores rurais do RS com renda bruta superior a R$ 360 mil."},"content":{"rendered":"\n<p>Com implementa\u00e7\u00e3o gradual, medida passa a valer para todos, independentemente do faturamento, somente em janeiro de 2026.<\/p>\n\n\n\n<p>A partir de fevereiro deste ano, come\u00e7a uma nova etapa do avan\u00e7o gradual da obrigatoriedade da\u00a0<a href=\"https:\/\/leouve.com.br\/?s=Nota+Fiscal+Eletr%C3%B4nica\"><strong>Nota Fiscal Eletr\u00f4nica (NF-e)<\/strong>\u00a0<\/a>e da Nota Fiscal de Consumidor Eletr\u00f4nica (NFC-e) para produtores rurais no Rio Grande do Sul. A alternativa digital j\u00e1 \u00e9 exigida para opera\u00e7\u00f5es interestaduais e substitui o modelo 4 da Nota Fiscal, conhecida como Nota do Produtor Rural ou \u2018tal\u00e3o do produtor\u2019.<\/p>\n\n\n\n<p>A medida foi aprovada pelo\u00a0<strong><a href=\"https:\/\/www.confaz.fazenda.gov.br\/\">Conselho Nacional de Pol\u00edtica Fazend\u00e1ria (Confaz)<\/a><\/strong>\u00a0no in\u00edcio de dezembro. A partir de 03 de fevereiro, o sistema de emiss\u00e3o eletr\u00f4nica deve ser usado nas opera\u00e7\u00f5es internas praticadas por todos os produtores rurais que, em 2023 ou 2024, obtiveram receita bruta de mais de R$ 360 mil com a atividade rural.<\/p>\n\n\n\n<p>A mudan\u00e7a abrange cerca de 50 mil profissionais da \u00e1rea no Estado. Quem j\u00e1 tem o tal\u00e3o impresso para emitir o modelo 4 poder\u00e1 seguir utilizando o documento at\u00e9 30 de junho. Em 1\u00ba de julho, o uso passa a ser vedado.<\/p>\n\n\n\n<p>J\u00e1 em 05 de janeiro de 2026, a obrigatoriedade da nota eletr\u00f4nica come\u00e7a a valer para todos os produtores rurais do Estado, independentemente do faturamento. A partir desta data, o modelo 4 n\u00e3o ser\u00e1 mais permitido.<\/p>\n\n\n\n<p>\u201cSer\u00e1 uma transi\u00e7\u00e3o lenta para que os produtores, especialmente os que t\u00eam menos estrutura, possam se adaptar. H\u00e1 algum tempo tamb\u00e9m j\u00e1 estamos fazendo capacita\u00e7\u00f5es junto a sindicatos para auxiliar e tirar d\u00favidas sobre a emiss\u00e3o da nota eletr\u00f4nica\u201d, explicou o chefe-adjunto da Se\u00e7\u00e3o de Informa\u00e7\u00f5es Fiscais da Receita Estadual, Geraldo Callegari.<\/p>\n\n\n\n<p>Desde 2021, produtores rurais que registraram faturamento superior a R$ 4,8 milh\u00f5es no ano de 2017 est\u00e3o obrigados a emitir as notas eletr\u00f4nicas em opera\u00e7\u00f5es internas. A previs\u00e3o era de que a medida se estendesse para outro grupo a partir de maio de 2024, mas, em raz\u00e3o das enchentes, a entrada em vigor foi adiada. O pedido partiu da Secretaria da Fazenda (Sefaz).<\/p>\n\n\n\n<p>\u201cUm n\u00famero muito alto de produtores foi afetado pela cat\u00e1strofe meteorol\u00f3gica vivida pelo Estado ga\u00facho. Naquele momento, entendemos que n\u00e3o fazia sentido que passasse a vigorar uma nova regra. Isso fez com que esses profissionais, t\u00e3o essenciais para a nossa economia, ganhassem tempo para reconstruir seus neg\u00f3cios\u201d, afirmou o subsecret\u00e1rio da Receita Estadual, Ricardo Neves Pereira.<\/p>\n\n\n\n<p><strong>Saiba como emitir a NF-e<\/strong><\/p>\n\n\n\n<p>A NF-e \u00e9 tamb\u00e9m chamada de modelo 55 e \u00e9 utilizada para registrar a venda de mercadorias e a presta\u00e7\u00e3o de servi\u00e7os. J\u00e1 a NFC-e, ou modelo 65, \u00e9 espec\u00edfica para o varejo e contempla as vendas diretas ao consumidor final.<\/p>\n\n\n\n<p>Existem diferentes alternativas para fazer a emiss\u00e3o desses modelos. Entre elas, est\u00e3o aplicativos pr\u00f3prios, aplicativos desenvolvidos por associa\u00e7\u00f5es\/cooperativas ou o sistema Nota Fiscal Avulsa (NFA-e), disponibilizado pela Sefaz. Essa \u00faltima op\u00e7\u00e3o, no entanto, s\u00f3 pode ser utilizada no computador e exige maior conhecimento t\u00e9cnico.<\/p>\n\n\n\n<p>A solu\u00e7\u00e3o recomendada pela pasta fazend\u00e1ria \u00e9 o aplicativo Nota Fiscal F\u00e1cil (NFF), que pode ser baixado gratuitamente no celular e acessado por meio do login gov.br. A ferramenta permite a emiss\u00e3o simplificada da nota fiscal, deixando toda a complexidade tribut\u00e1ria a cargo da Receita Estadual.<\/p>\n\n\n\n<p>Para usar, os produtores devem preencher informa\u00e7\u00f5es sobre a venda, como o produto, o cliente e dados sobre transporte. \u00c9 poss\u00edvel, inclusive, gerar um QR Code da nota fiscal off-line, no meio da lavoura, por exemplo. Nesse caso, a nota \u00e9 autorizada ap\u00f3s o restabelecimento da conex\u00e3o com a internet.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/leouve.com.br\/estado\/nota-eletronica-sera-obrigatoria-para-produtores-rurais-do-rs-com-renda-bruta-superior-a-r-360-mil\/\">Leouve<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com implementa\u00e7\u00e3o gradual, medida passa a valer para todos, independentemente do faturamento, somente em janeiro de 2026. A partir de [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":771,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/770\/revisions\/771"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}