{"id":834,"date":"2025-10-15T14:15:42","date_gmt":"2025-10-15T17:15:42","guid":{"rendered":"https:\/\/wsoftnet.com.br\/wsblog\/?p=834"},"modified":"2025-10-15T14:15:43","modified_gmt":"2025-10-15T17:15:43","slug":"producao-da-industria-paulista-cresce-08-em-agosto-informa-ibge","status":"publish","type":"post","link":"https:\/\/wsoftnet.com.br\/wsblog\/producao-da-industria-paulista-cresce-08-em-agosto-informa-ibge\/","title":{"rendered":"Produ\u00e7\u00e3o da ind\u00fastria paulista cresce 0,8% em agosto, informa IBGE."},"content":{"rendered":"\n<p>Na m\u00e9dia global, a produ\u00e7\u00e3o cresceu em nove das 15 localidades pesquisadas no comparativo mensal, levando a ind\u00fastria nacional a uma alta de 0,8%.<\/p>\n\n\n\n<p>O crescimento de 0,8% na produ\u00e7\u00e3o da ind\u00fastria de S\u00e3o Paulo em agosto ante julho foi o segundo m\u00eas seguido de expans\u00e3o, per\u00edodo em que acumulou um ganho de 1,7%. Os dados s\u00e3o da Pesquisa Industrial Mensal divulgada, nesta sexta-feira, 10\/10, pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE).<\/p>\n\n\n\n<p>A ind\u00fastria de S\u00e3o Paulo, maior parque fabril do pa\u00eds, operava em agosto em patamar 0,5% acima do registrado no pr\u00e9-pandemia, em fevereiro de 2020, mas ainda 21,2% aqu\u00e9m do pico hist\u00f3rico de produ\u00e7\u00e3o alcan\u00e7ado em mar\u00e7o de 2011.<\/p>\n\n\n\n<p>Na passagem de julho para agosto, o avan\u00e7o na ind\u00fastria paulista foi impulsionado pelos setores extrativo e de alimentos.<\/p>\n\n\n\n<p><strong>Brasil<\/strong>&nbsp;\u2013 A produ\u00e7\u00e3o industrial cresceu em nove dos 15 locais pesquisados em agosto. Houve expans\u00e3o no Par\u00e1 (5,4%), Bahia (4,9%), Paran\u00e1 (4,2%), Rio Grande do Sul (2,9%), Mato Grosso (1,4%), Goi\u00e1s (1,4%), Regi\u00e3o Nordeste (1,0%), S\u00e3o Paulo (0,8%) e Esp\u00edrito Santo (0,4%).<\/p>\n\n\n\n<p>Na dire\u00e7\u00e3o oposta, houve perdas no Amazonas (-7,4%), Pernambuco (-3,5%), Rio de Janeiro (-1,9%), Santa Catarina (-1,8%), Cear\u00e1 (-1,5%) e Minas Gerais (-0,2%).<\/p>\n\n\n\n<p>Na m\u00e9dia global, a ind\u00fastria nacional avan\u00e7ou 0,8% em agosto na varia\u00e7\u00e3o mensal.<\/p>\n\n\n\n<p><strong>Faturamento<\/strong><\/p>\n\n\n\n<p>O faturamento das f\u00e1bricas brasileiras caiu 5,3% em agosto, de acordo com os Indicadores Industriais divulgados pela Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI). O desempenho negativo em rela\u00e7\u00e3o a julho j\u00e1 considera os dados dessazonalizados.<\/p>\n\n\n\n<p>Na compara\u00e7\u00e3o com agosto do ano passado, a queda nas vendas do setor foi de 7,6%.<\/p>\n\n\n\n<p>Mesmo com a quarta queda no indicador em seis meses, o desempenho de janeiro a agosto deste ano ainda \u00e9 2,9% melhor que o registrado nos primeiros oito meses de 2024.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/dcomercio.com.br\/publicacao\/s\/producao-da-industria-paulista-cresce-0-8-em-agosto-informa-ibge\">Di\u00e1rio do Com\u00e9rcio<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na m\u00e9dia global, a produ\u00e7\u00e3o cresceu em nove das 15 localidades pesquisadas no comparativo mensal, levando a ind\u00fastria nacional a [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-834","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/comments?post=834"}],"version-history":[{"count":1,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/834\/revisions"}],"predecessor-version":[{"id":835,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/posts\/834\/revisions\/835"}],"wp:attachment":[{"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/media?parent=834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/categories?post=834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wsoftnet.com.br\/wsblog\/wp-json\/wp\/v2\/tags?post=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}